{"id":59,"date":"2018-01-17T15:25:27","date_gmt":"2018-01-17T15:25:27","guid":{"rendered":"https:\/\/www.padelen.com\/blog\/?p=59"},"modified":"2018-05-27T14:12:27","modified_gmt":"2018-05-27T14:12:27","slug":"indoor-vs-exterior","status":"publish","type":"post","link":"https:\/\/www.padelen.com\/blog\/pistas-de-padel\/indoor-vs-exterior\/","title":{"rendered":"Pistas de p\u00e1del indoor vs pistas de p\u00e1del exterior"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;59&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Pistas de p\u00e1del indoor vs pistas de p\u00e1del exterior&quot;,&quot;width&quot;:&quot;138&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 138px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (1 voto)    <\/div>\n    <\/div>\n<p align=\"justify\">Hist\u00f3ricamente el deporte del p\u00e1del naci\u00f3 como deporte al aire libre y m\u00e1s concretamente en pistas de muro. Pero con el paso de los a\u00f1os, su evoluci\u00f3n le ha llevado a dar prioridad a los clubes de p\u00e1del indoor en pistas de cristal. Ante estas posibilidades, \u00bfes mejor jugar al p\u00e1del al aire libre o en el interior?<\/p>\n<p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-77 aligncenter\" title=\"Pistas de p\u00e1del Indoor vs Pistas de p\u00e1del Outdoor\" src=\"https:\/\/www.padelen.com\/blog\/wp-content\/uploads\/2018\/01\/PistasIndoorvsOutdoor.jpg\" alt=\"Pistas de p\u00e1del Indoor vs Outdoor\" width=\"1024\" height=\"512\" srcset=\"https:\/\/www.padelen.com\/blog\/wp-content\/uploads\/2018\/01\/PistasIndoorvsOutdoor.jpg 1024w, https:\/\/www.padelen.com\/blog\/wp-content\/uploads\/2018\/01\/PistasIndoorvsOutdoor-300x150.jpg 300w, https:\/\/www.padelen.com\/blog\/wp-content\/uploads\/2018\/01\/PistasIndoorvsOutdoor-768x384.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2>Pista de p\u00e1del indoor<\/h2>\n<p align=\"justify\">Una pista de p\u00e1del indoor es una pista que est\u00e1 totalmente cubierta, es decir, lo que llamariamos una pista <em>de interior<\/em>.<\/p>\n<h3>Ventajas<\/h3>\n<ul>\n<li>Climatolog\u00eda: a nadie se le escapa que la principal ventaja de la pistas de p\u00e1del indoor es que nos protege de las condiciones meteorol\u00f3gcas adversas, te olvidas de la lluvia y el viento. Tambi\u00e9n te olvidar\u00e1s del reflejo del sol.<\/li>\n<li>Estado de la pista: en general al estar protegidas del exterior su estado suele ser mejor que las pistas outdoor.<\/li>\n<li>Pistas de cristal: la mayor\u00eda de pistas indoor son acristaladas.<\/li>\n<\/ul>\n<h3>Inconvenientes<\/h3>\n<p align=\"justify\">Jugar al p\u00e1del en pista de p\u00e1del indoor tiene sus ventajas, pero como todo, tambi\u00e9n tiene algunos inconvenientes.<\/p>\n<ul>\n<li>Climatizaci\u00f3n: muchos clubes de p\u00e1del indoor no cuentan con sistemas de climatizaci\u00f3n. Esto supone un problema durante la temporada estival por las altas temperaturas que se concentran en el interior del club y en la temporada invernal por el fr\u00edo.<\/li>\n<li>Altura: un factor determinante del p\u00e1del indoor es la altura del techo que nos puede condicionar en gran medida los globos.<\/li>\n<li>Luz artificial: aunque no todos los jugadores lo consideran un problema.<\/li>\n<li>Ruido: especialmente si se trata de clubes peque\u00f1os o pistas encerradas en espacios peque\u00f1os.<\/li>\n<\/ul>\n<h2>Pista de p\u00e1del exterior<\/h2>\n<p align=\"justify\">Como su propio nombre indica, una pista exterior, tambi\u00e9n conocida como outdoor, es aquella que est\u00e1 al aire libre.<\/p>\n<h3>Ventajas<\/h3>\n<ul>\n<li>Sensaci\u00f3n de libertad: se trata de un lugar abierto, en general, la sensaci\u00f3n de libertad ser\u00e1 mayor.<\/li>\n<li>Altura libre: en el exterior no hay limitaci\u00f3n de altura. Podr\u00e1s lanzar los globos o contras tan altos como necesites.<\/li>\n<\/ul>\n<h3>Inconvenientes<\/h3>\n<ul>\n<li>Climatolog\u00eda: en oposici\u00f3n a las pistas indoor, estamos sometidos al viento, reflejos solares y en el peor de los casos a la lluvia. Las altas\/bajas temperaturas tambi\u00e9n pueden ser un problema, as\u00ed como la humedad que empa\u00f1a los cristales.<\/li>\n<\/ul>\n<div class=\"su-quote su-quote-style-default\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\">\u00bfY tu, eres de pista indoor o exterior?<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hist\u00f3ricamente el deporte del p\u00e1del naci\u00f3 como deporte al aire libre y m\u00e1s concretamente en pistas de muro. Pero con el paso de los a\u00f1os, su evoluci\u00f3n le ha llevado a dar prioridad a los clubes de p\u00e1del indoor en pistas de cristal. Ante estas posibilidades, \u00bfes mejor jugar al p\u00e1del al aire libre o en el interior? Pista de p\u00e1del indoor Una pista de p\u00e1del indoor es una pista que est\u00e1 totalmente cubierta, es decir, lo que llamariamos una pista de interior. Ventajas Climatolog\u00eda: a nadie se le escapa que la principal ventaja de la pistas de p\u00e1del indoor <\/p>\n","protected":false},"author":1,"featured_media":77,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-59","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pistas-de-padel","has_thumb"],"_links":{"self":[{"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/posts\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/comments?post=59"}],"version-history":[{"count":22,"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/posts\/59\/revisions"}],"predecessor-version":[{"id":468,"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/posts\/59\/revisions\/468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/media\/77"}],"wp:attachment":[{"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/media?parent=59"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/categories?post=59"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padelen.com\/blog\/wp-json\/wp\/v2\/tags?post=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}